{"id":564,"date":"2024-10-15T17:31:21","date_gmt":"2024-10-15T15:31:21","guid":{"rendered":"https:\/\/laserwall.it\/web\/?page_id=564"},"modified":"2026-01-29T11:36:11","modified_gmt":"2026-01-29T09:36:11","slug":"contattaci","status":"publish","type":"page","link":"https:\/\/laserwall.it\/web\/contattaci","title":{"rendered":"Contattaci"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" style=\"margin-top:0;margin-bottom:0\">Contattaci<\/h2>\n\n\n\n<p style=\"margin-top:0;margin-bottom:0\">Che tu sia un amministratore, un cond\u00f2mino, un&#8217;azienda o un ente, contattaci! <br>Se ci contatti per una <strong>richiesta urgente sulla videosorveglianza<\/strong>, telefona in orario ufficio al <strong>+39 0282197028<\/strong> o fuori orario tramite l\u2019email\u00a0<strong><em>videosorveglianza@laserwall.it<\/em>\u00a0<\/strong> (indica sempre il condominio e la scala. Ti ricordiamo che le immagini vengono conservate <strong>non oltre le 48 ore dal momento della loro registrazione<\/strong>, dopodich\u00e9 le stesse\u00a0<strong>vengono automaticamente cancellate<\/strong>).<br><br><strong>Scegli come prima cosa chi sei e prosegui con il modulo:<\/strong><\/p>\n\n\n<style>\n       .errordiv { padding:10px; margin:10px; border: 1px solid #555555;color: #000000;background-color: #f8f8f8; width:500px; }#advanced_iframe {visibility:visible;opacity:1;vertical-align:top;}.ai-info-bottom-iframe { position: fixed; z-index: 10000; bottom:0; left: 0; margin: 0px; text-align: center; width: 100%; background-color: #ff9999; padding-left: 5px;padding-bottom: 5px; border-top: 1px solid #aaa } a.ai-bold {font-weight: bold;}#ai-layer-div-advanced_iframe p {height:100%;margin:0;padding:0}<\/style><script type=\"text\/javascript\">var ai_iframe_width_advanced_iframe = 0;var ai_iframe_height_advanced_iframe = 0;var aiOnloadScrollTop=\"true\";var aiShowDebug=false;\n\t\tif (typeof aiReadyCallbacks === 'undefined') {\n\t\t\tvar aiReadyCallbacks = [];\n\t\t} else if (!(aiReadyCallbacks instanceof Array)) {\n\t\t\tvar aiReadyCallbacks = [];\n\t\t}    function aiShowIframeId(id_iframe) { jQuery(\"#\"+id_iframe).css(\"visibility\", \"visible\");    }    function aiResizeIframeHeight(height) { aiResizeIframeHeight(height,advanced_iframe); }    function aiResizeIframeHeightId(height,width,id) {aiResizeIframeHeightById(id,height);}<\/script><iframe id=\"advanced_iframe\"  name=\"advanced_iframe\"  src=\"https:\/\/laserwall.it\/iframe-wp\/#\/it\/contacts\"  width=\"100%\"  height=\"900\"  frameborder=\"0\"  border=\"0\"  allowtransparency=\"true\"  loading=\"lazy\"  style=\";border-width: 0px;;border: none;;width:100%;;height:900px;\" ><\/iframe><script type=\"text\/javascript\">var ifrm_advanced_iframe = document.getElementById(\"advanced_iframe\");var hiddenTabsDoneadvanced_iframe = false;\nfunction resizeCallbackadvanced_iframe() {}<\/script><script type=\"text\/javascript\"><\/script><p style=\"display:block !important; visibility:visible !important;margin: -18px 14px 0 0;padding-left: 3px;padding-top:3px;background: white; overflow: hidden; position: relative; line-height:15px;width: fit-content;\"><small style=\"display:block !important;visibility:visible !important\">powered by Advanced iFrame<\/small><\/p>","protected":false},"excerpt":{"rendered":"<p>Contattaci Che tu sia un amministratore, un cond\u00f2mino, un&#8217;azienda o un ente, contattaci! Se ci contatti per una richiesta urgente sulla videosorveglianza, telefona in orario ufficio al +39 0282197028 o fuori orario tramite l\u2019email\u00a0videosorveglianza@laserwall.it\u00a0 (indica sempre il condominio e la scala. Ti ricordiamo che le immagini vengono conservate non oltre le 48 ore dal momento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-564","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contattaci - Laserwall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laserwall.it\/web\/contattaci\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contattaci - Laserwall\" \/>\n<meta property=\"og:description\" content=\"Contattaci Che tu sia un amministratore, un cond\u00f2mino, un&#8217;azienda o un ente, contattaci! Se ci contatti per una richiesta urgente sulla videosorveglianza, telefona in orario ufficio al +39 0282197028 o fuori orario tramite l\u2019email\u00a0videosorveglianza@laserwall.it\u00a0 (indica sempre il condominio e la scala. Ti ricordiamo che le immagini vengono conservate non oltre le 48 ore dal momento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laserwall.it\/web\/contattaci\" \/>\n<meta property=\"og:site_name\" content=\"Laserwall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laserwallsrl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T09:36:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laserwall.it\/web\/wp-content\/uploads\/2024\/11\/laserwall-sito.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Laserwall112459\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/contattaci\",\"url\":\"https:\\\/\\\/laserwall.it\\\/web\\\/contattaci\",\"name\":\"Contattaci - Laserwall\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/#website\"},\"datePublished\":\"2024-10-15T15:31:21+00:00\",\"dateModified\":\"2026-01-29T09:36:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/contattaci#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laserwall.it\\\/web\\\/contattaci\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/contattaci#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laserwall.it\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contattaci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/laserwall.it\\\/web\\\/\",\"name\":\"Laserwall\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laserwall.it\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/#organization\",\"name\":\"Laserwall\",\"url\":\"https:\\\/\\\/laserwall.it\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/laserwall.it\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-logo2024-2.png\",\"contentUrl\":\"https:\\\/\\\/laserwall.it\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-logo2024-2.png\",\"width\":180,\"height\":60,\"caption\":\"Laserwall\"},\"image\":{\"@id\":\"https:\\\/\\\/laserwall.it\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laserwallsrl\",\"https:\\\/\\\/x.com\\\/Laserwall112459\",\"https:\\\/\\\/www.instagram.com\\\/laserwallsrl\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laserwall-srl\",\"https:\\\/\\\/www.youtube.com\\\/@laserwallsrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contattaci - Laserwall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laserwall.it\/web\/contattaci","og_locale":"it_IT","og_type":"article","og_title":"Contattaci - Laserwall","og_description":"Contattaci Che tu sia un amministratore, un cond\u00f2mino, un&#8217;azienda o un ente, contattaci! Se ci contatti per una richiesta urgente sulla videosorveglianza, telefona in orario ufficio al +39 0282197028 o fuori orario tramite l\u2019email\u00a0videosorveglianza@laserwall.it\u00a0 (indica sempre il condominio e la scala. Ti ricordiamo che le immagini vengono conservate non oltre le 48 ore dal momento [&hellip;]","og_url":"https:\/\/laserwall.it\/web\/contattaci","og_site_name":"Laserwall","article_publisher":"https:\/\/www.facebook.com\/laserwallsrl","article_modified_time":"2026-01-29T09:36:11+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/laserwall.it\/web\/wp-content\/uploads\/2024\/11\/laserwall-sito.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@Laserwall112459","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laserwall.it\/web\/contattaci","url":"https:\/\/laserwall.it\/web\/contattaci","name":"Contattaci - Laserwall","isPartOf":{"@id":"https:\/\/laserwall.it\/web\/#website"},"datePublished":"2024-10-15T15:31:21+00:00","dateModified":"2026-01-29T09:36:11+00:00","breadcrumb":{"@id":"https:\/\/laserwall.it\/web\/contattaci#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laserwall.it\/web\/contattaci"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/laserwall.it\/web\/contattaci#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/laserwall.it\/web\/"},{"@type":"ListItem","position":2,"name":"Contattaci"}]},{"@type":"WebSite","@id":"https:\/\/laserwall.it\/web\/#website","url":"https:\/\/laserwall.it\/web\/","name":"Laserwall","description":"","publisher":{"@id":"https:\/\/laserwall.it\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laserwall.it\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/laserwall.it\/web\/#organization","name":"Laserwall","url":"https:\/\/laserwall.it\/web\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/laserwall.it\/web\/#\/schema\/logo\/image\/","url":"https:\/\/laserwall.it\/web\/wp-content\/uploads\/2024\/10\/cropped-logo2024-2.png","contentUrl":"https:\/\/laserwall.it\/web\/wp-content\/uploads\/2024\/10\/cropped-logo2024-2.png","width":180,"height":60,"caption":"Laserwall"},"image":{"@id":"https:\/\/laserwall.it\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laserwallsrl","https:\/\/x.com\/Laserwall112459","https:\/\/www.instagram.com\/laserwallsrl\/","https:\/\/www.linkedin.com\/company\/laserwall-srl","https:\/\/www.youtube.com\/@laserwallsrl"]}]}},"_links":{"self":[{"href":"https:\/\/laserwall.it\/web\/wp-json\/wp\/v2\/pages\/564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserwall.it\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/laserwall.it\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/laserwall.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laserwall.it\/web\/wp-json\/wp\/v2\/comments?post=564"}],"version-history":[{"count":22,"href":"https:\/\/laserwall.it\/web\/wp-json\/wp\/v2\/pages\/564\/revisions"}],"predecessor-version":[{"id":2813,"href":"https:\/\/laserwall.it\/web\/wp-json\/wp\/v2\/pages\/564\/revisions\/2813"}],"wp:attachment":[{"href":"https:\/\/laserwall.it\/web\/wp-json\/wp\/v2\/media?parent=564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}